{"id":55631,"date":"2026-03-30T11:36:54","date_gmt":"2026-03-30T09:36:54","guid":{"rendered":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/"},"modified":"2026-07-15T12:49:26","modified_gmt":"2026-07-15T10:49:26","slug":"ziggy-cocktail-glas-svart","status":"publish","type":"product","link":"https:\/\/olssonjensen.se\/en\/product\/ziggy-cocktail-glas-svart\/","title":{"rendered":"Ziggy cocktail glass black"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cocktail glass that combines classic form with a playful striped expression. Available in multiple colors.<\/p>","protected":false},"featured_media":58452,"template":"","meta":{"_acf_changed":false,"oj_sales_app_outofstock_delivery_text":""},"product_brand":[],"product_cat":[112],"product_tag":[],"class_list":["post-55631","product","type-product","status-publish","has-post-thumbnail","product_cat-nyheter","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"meta_data":[],"shsp-ext":{"main":{},"variations":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ziggy cocktailglas svart - Olsson &amp; Jensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olssonjensen.se\/en\/product\/ziggy-cocktail-glas-svart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ziggy cocktailglas svart - Olsson &amp; Jensen\" \/>\n<meta property=\"og:description\" content=\"Cocktailglas som kombinerar klassisk form med ett lekfullt randigt uttryck. Finns i fler f\u00e4rger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olssonjensen.se\/en\/product\/ziggy-cocktail-glas-svart\/\" \/>\n<meta property=\"og:site_name\" content=\"Olsson &amp; Jensen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olssonjensen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:49:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olssonjensen.se\/wp-content\/uploads\/2026\/06\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/\",\"url\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/\",\"name\":\"Ziggy cocktailglas svart - Olsson &amp; Jensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olssonjensen.se\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg\",\"datePublished\":\"2026-03-30T09:36:54+00:00\",\"dateModified\":\"2026-07-15T10:49:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olssonjensen.se\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg\",\"contentUrl\":\"https:\\\/\\\/olssonjensen.se\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg\",\"width\":1280,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/produkt\\\/ziggy-cocktail-glas-svart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/olssonjensen.se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olssonjensen.se\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ziggy cocktailglas svart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#website\",\"url\":\"https:\\\/\\\/olssonjensen.se\\\/\",\"name\":\"Olsson & Jensen\",\"description\":\"Inredning, vintagem\u00f6bler och mycket mer\",\"publisher\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olssonjensen.se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#organization\",\"name\":\"Olsson & Jensen\",\"url\":\"https:\\\/\\\/olssonjensen.se\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olssonjensen.se\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/oj_google.png\",\"contentUrl\":\"https:\\\/\\\/olssonjensen.se\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/oj_google.png\",\"width\":800,\"height\":615,\"caption\":\"Olsson & Jensen\"},\"image\":{\"@id\":\"https:\\\/\\\/olssonjensen.se\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olssonjensen\",\"https:\\\/\\\/www.instagram.com\\\/olssonjensen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ziggy cocktailglas svart - Olsson &amp; Jensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olssonjensen.se\/en\/product\/ziggy-cocktail-glas-svart\/","og_locale":"en_US","og_type":"article","og_title":"Ziggy cocktailglas svart - Olsson &amp; Jensen","og_description":"Cocktailglas som kombinerar klassisk form med ett lekfullt randigt uttryck. Finns i fler f\u00e4rger.","og_url":"https:\/\/olssonjensen.se\/en\/product\/ziggy-cocktail-glas-svart\/","og_site_name":"Olsson &amp; Jensen","article_publisher":"https:\/\/www.facebook.com\/olssonjensen","article_modified_time":"2026-07-15T10:49:26+00:00","og_image":[{"width":1280,"height":1920,"url":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2026\/06\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/","url":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/","name":"Ziggy cocktailglas svart - Olsson &amp; Jensen","isPartOf":{"@id":"https:\/\/olssonjensen.se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/#primaryimage"},"image":{"@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/#primaryimage"},"thumbnailUrl":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2026\/06\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg","datePublished":"2026-03-30T09:36:54+00:00","dateModified":"2026-07-15T10:49:26+00:00","breadcrumb":{"@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/#primaryimage","url":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2026\/06\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg","contentUrl":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2026\/06\/Olsson_Jensen_Dazed_Haze_AW26_\u00a9_ONI_Studio_37096-8.jpg","width":1280,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/olssonjensen.se\/produkt\/ziggy-cocktail-glas-svart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/olssonjensen.se\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olssonjensen.se\/shop\/"},{"@type":"ListItem","position":3,"name":"Ziggy cocktailglas svart"}]},{"@type":"WebSite","@id":"https:\/\/olssonjensen.se\/#website","url":"https:\/\/olssonjensen.se\/","name":"Olsson &amp; Jensen","description":"Interior design, vintage furniture, and much more","publisher":{"@id":"https:\/\/olssonjensen.se\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olssonjensen.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olssonjensen.se\/#organization","name":"Olsson &amp; Jensen","url":"https:\/\/olssonjensen.se\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olssonjensen.se\/#\/schema\/logo\/image\/","url":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2022\/10\/oj_google.png","contentUrl":"https:\/\/olssonjensen.se\/wp-content\/uploads\/2022\/10\/oj_google.png","width":800,"height":615,"caption":"Olsson & Jensen"},"image":{"@id":"https:\/\/olssonjensen.se\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olssonjensen","https:\/\/www.instagram.com\/olssonjensen\/"]}]}},"sales_app_outofstock_delivery_text":"","price_excl_tax":"8","_links":{"self":[{"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/product\/55631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/media\/58452"}],"wp:attachment":[{"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/media?parent=55631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/product_brand?post=55631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/product_cat?post=55631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olssonjensen.se\/en\/wp-json\/wp\/v2\/product_tag?post=55631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}